{"id":3408,"date":"2026-06-19T09:55:45","date_gmt":"2026-06-19T09:55:45","guid":{"rendered":"https:\/\/lab-partners.nl\/?post_type=nieuws&#038;p=3408"},"modified":"2026-07-14T10:31:41","modified_gmt":"2026-07-14T10:31:41","slug":"fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2","status":"publish","type":"nieuws","link":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/","title":{"rendered":"Beckman Coulter DxA Live bei SWLP St. Helier"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3408\" class=\"elementor elementor-3408 elementor-3407\" data-elementor-post-type=\"nieuws\">\n\t\t\t\t<div class=\"elementor-element elementor-element-168e8ffe e-flex e-con-boxed e-con e-parent\" data-id=\"168e8ffe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c91b080 margin-top-3 margin-bottom-3 e-flex e-con-boxed e-con e-child\" data-id=\"c91b080\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-285c110 color-1 font-size-3 margin-bottom-1 elementor-widget elementor-widget-heading\" data-id=\"285c110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Beckman Coulter DxA Live bei SWLP St. Helier<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65af305c elementor-widget elementor-widget-text-editor\" data-id=\"65af305c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nach fast einem Jahr der Vorbereitung wurde bei South West London Pathology St Helier ein wichtiger Meilenstein erreicht: Das vollautomatisierte DxA-System von Beckman Coulter Diagnostics ist nun in Betrieb genommen worden.<\/p>\n<p>Was mit einer ersten Evaluierung begann, entwickelte sich \u00fcber Monate hinweg zu Renovierungsarbeiten, Umstrukturierungen und dem Betrieb neuer Analyseger\u00e4te im Stand-alone-Modus. W\u00e4hrend dieses gesamten Prozesses waren die Flexibilit\u00e4t und das Engagement aller Beteiligten von entscheidender Bedeutung, um diesen \u00dcbergang zu einem Erfolg zu machen.<\/p>\n<p>Trotz des Umfangs und der Komplexit\u00e4t der Umstellung in einer rund um die Uhr betriebenen Laborumgebung verlief die Inbetriebnahme reibungslos und ohne gr\u00f6\u00dfere R\u00fcckschl\u00e4ge. Dies zeugt von der engen Zusammenarbeit aller beteiligten Parteien, darunter das Estates-Team des Epsom and St Helier University Hospitals NHS Trust.<\/p>\n<p>Unser besonderer Dank gilt Steve Hopkins f\u00fcr seine Unterst\u00fctzung sowie Martin Standring f\u00fcr seine F\u00fchrungsrolle als Projektmanager. Wir m\u00f6chten uns auch bei allen Technikern und Spezialisten von Beckman Coulter Diagnostics EMEA bedanken, die die Installation mit gro\u00dfer Pr\u00e4zision und Engagement durchgef\u00fchrt haben: vom Aufbau \u00fcber die Abnahme bis hin zur fortlaufenden Betreuung.<br \/>Ein Ergebnis, auf das wir stolz sein k\u00f6nnen, und ein wunderbares Beispiel daf\u00fcr, was durch enge Zusammenarbeit erreicht werden kann. \ud83d\ude80<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59bcb9d elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"59bcb9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.linkedin.com\/feed\/update\/urn:li:activity:7473740318077644800\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"11\" viewBox=\"0 0 17 11\" fill=\"none\"><path d=\"M15.7812 6.03125L11.5312 10.2812C11.2188 10.5938 10.75 10.5938 10.4688 10.2812C10.1562 10 10.1562 9.53125 10.4688 9.21875L13.4375 6.25H0.75C0.3125 6.25 0 5.9375 0 5.5C0 5.09375 0.3125 4.75 0.75 4.75H13.4375L10.4688 1.78125C10.1562 1.5 10.1562 1.03125 10.4688 0.71875C10.75 0.4375 11.2188 0.4375 11.5312 0.71875L15.7812 5C16.0625 5.28125 16.0625 5.75 15.7812 6.03125Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Diesen Beitrag auf LinkedIn ansehen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48fe6a4 elementor-widget elementor-widget-image\" data-id=\"48fe6a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/lab-partners.nl\/wp-content\/uploads\/2026\/06\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c.jpeg\" class=\"attachment-medium_large size-medium_large wp-image-3415\" alt=\"\" srcset=\"https:\/\/lab-partners.nl\/wp-content\/uploads\/2026\/06\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c.jpeg 768w, https:\/\/lab-partners.nl\/wp-content\/uploads\/2026\/06\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c-225x300.jpeg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f84bcf elementor-widget elementor-widget-spacer\" data-id=\"6f84bcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nach fast einem Jahr der Vorbereitung wurde bei South West London Pathology St Helier ein wichtiger Meilenstein erreicht: Das vollautomatische DxA-System von Beckman Coulter Diagnostics wurde nun in Betrieb genommen.<\/p>\n","protected":false},"featured_media":3426,"template":"","class_list":["post-3408","nieuws","type-nieuws","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beckman Coulter DxA Live bei SWLP St. Helier - Lab-Partners<\/title>\n<meta name=\"description\" content=\"Nach fast einem Jahr der Vorbereitung wurde in St. Helier ein wichtiger Meilenstein erreicht: Das DxA-System von Beckman Coulter ist nun in Betrieb.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beckman Coulter DxA Live bei SWLP St. Helier - Lab-Partners\" \/>\n<meta property=\"og:description\" content=\"Nach fast einem Jahr der Vorbereitung wurde in St. Helier ein wichtiger Meilenstein erreicht: Das DxA-System von Beckman Coulter ist nun in Betrieb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Lab-Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61554663687106\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T10:31:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lab-partners.nl\/wp-content\/uploads\/2026\/06\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/nieuws\\\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\\\/\",\"url\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/nieuws\\\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\\\/\",\"name\":\"Beckman Coulter DxA Live bei SWLP St. Helier - Lab-Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/nieuws\\\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/nieuws\\\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lab-partners.nl\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c2.jpeg\",\"datePublished\":\"2026-06-19T09:55:45+00:00\",\"dateModified\":\"2026-07-14T10:31:41+00:00\",\"description\":\"Nach fast einem Jahr der Vorbereitung wurde in St. Helier ein wichtiger Meilenstein erreicht: Das DxA-System von Beckman Coulter ist nun in Betrieb.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/nieuws\\\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lab-partners.nl\\\/de\\\/nieuws\\\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/nieuws\\\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lab-partners.nl\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c2.jpeg\",\"contentUrl\":\"https:\\\/\\\/lab-partners.nl\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c2.jpeg\",\"width\":768,\"height\":614},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/nieuws\\\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachrichten\",\"item\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/nieuws\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beckman Coulter DxA Live bei SWLP St. Helier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/\",\"name\":\"Lab-Partners\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/#organization\",\"name\":\"Lab-Partners B.V.\",\"url\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lab-partners.cc-websolutions.nl\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/lab-partners.cc-websolutions.nl\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo.svg\",\"width\":207,\"height\":78,\"caption\":\"Lab-Partners B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/lab-partners.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61554663687106\",\"https:\\\/\\\/www.instagram.com\\\/labpartners_nl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lab-partners\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beckman Coulter DxA Live bei SWLP St. Helier - Lab-Partners","description":"Nach fast einem Jahr der Vorbereitung wurde in St. Helier ein wichtiger Meilenstein erreicht: Das DxA-System von Beckman Coulter ist nun in Betrieb.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/","og_locale":"de_DE","og_type":"article","og_title":"Beckman Coulter DxA Live bei SWLP St. Helier - Lab-Partners","og_description":"Nach fast einem Jahr der Vorbereitung wurde in St. Helier ein wichtiger Meilenstein erreicht: Das DxA-System von Beckman Coulter ist nun in Betrieb.","og_url":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/","og_site_name":"Lab-Partners","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61554663687106","article_modified_time":"2026-07-14T10:31:41+00:00","og_image":[{"width":768,"height":614,"url":"https:\/\/lab-partners.nl\/wp-content\/uploads\/2026\/06\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c2.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/","url":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/","name":"Beckman Coulter DxA Live bei SWLP St. Helier - Lab-Partners","isPartOf":{"@id":"https:\/\/lab-partners.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/#primaryimage"},"image":{"@id":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/#primaryimage"},"thumbnailUrl":"https:\/\/lab-partners.nl\/wp-content\/uploads\/2026\/06\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c2.jpeg","datePublished":"2026-06-19T09:55:45+00:00","dateModified":"2026-07-14T10:31:41+00:00","description":"Nach fast einem Jahr der Vorbereitung wurde in St. Helier ein wichtiger Meilenstein erreicht: Das DxA-System von Beckman Coulter ist nun in Betrieb.","breadcrumb":{"@id":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/#primaryimage","url":"https:\/\/lab-partners.nl\/wp-content\/uploads\/2026\/06\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c2.jpeg","contentUrl":"https:\/\/lab-partners.nl\/wp-content\/uploads\/2026\/06\/35E479BF-7D9B-4A3A-811D-43857FDA83C1_1_105_c2.jpeg","width":768,"height":614},{"@type":"BreadcrumbList","@id":"https:\/\/lab-partners.nl\/de\/nieuws\/fuji-europe-africa-zieht-in-neue-raumlichkeiten-in-wageningen-um-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lab-partners.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Nachrichten","item":"https:\/\/lab-partners.nl\/de\/nieuws\/"},{"@type":"ListItem","position":3,"name":"Beckman Coulter DxA Live bei SWLP St. Helier"}]},{"@type":"WebSite","@id":"https:\/\/lab-partners.nl\/de\/#website","url":"https:\/\/lab-partners.nl\/de\/","name":"Lab-Partners","description":"","publisher":{"@id":"https:\/\/lab-partners.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lab-partners.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/lab-partners.nl\/de\/#organization","name":"Lab-Partners B.V.","url":"https:\/\/lab-partners.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/lab-partners.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/lab-partners.cc-websolutions.nl\/wp-content\/uploads\/2024\/02\/logo.svg","contentUrl":"https:\/\/lab-partners.cc-websolutions.nl\/wp-content\/uploads\/2024\/02\/logo.svg","width":207,"height":78,"caption":"Lab-Partners B.V."},"image":{"@id":"https:\/\/lab-partners.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61554663687106","https:\/\/www.instagram.com\/labpartners_nl","https:\/\/www.linkedin.com\/company\/lab-partners"]}]}},"_links":{"self":[{"href":"https:\/\/lab-partners.nl\/de\/wp-json\/wp\/v2\/nieuws\/3408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lab-partners.nl\/de\/wp-json\/wp\/v2\/nieuws"}],"about":[{"href":"https:\/\/lab-partners.nl\/de\/wp-json\/wp\/v2\/types\/nieuws"}],"version-history":[{"count":3,"href":"https:\/\/lab-partners.nl\/de\/wp-json\/wp\/v2\/nieuws\/3408\/revisions"}],"predecessor-version":[{"id":3423,"href":"https:\/\/lab-partners.nl\/de\/wp-json\/wp\/v2\/nieuws\/3408\/revisions\/3423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lab-partners.nl\/de\/wp-json\/wp\/v2\/media\/3426"}],"wp:attachment":[{"href":"https:\/\/lab-partners.nl\/de\/wp-json\/wp\/v2\/media?parent=3408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}